{"id":406,"date":"2016-03-20T15:33:24","date_gmt":"2016-03-20T14:33:24","guid":{"rendered":"http:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color.jpg"},"modified":"2016-03-20T15:33:24","modified_gmt":"2016-03-20T14:33:24","slug":"sort-nederdel-united-color","status":"inherit","type":"attachment","link":"https:\/\/caresharevintage.dk\/en\/?attachment_id=406","title":{"rendered":"Sort nederdel united color"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582.jpg'><img width=\"161\" height=\"300\" src=\"https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582-161x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582-161x300.jpg 161w, https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582-300x561.jpg 300w, https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582-600x1121.jpg 600w, https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582-80x150.jpg 80w, https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582-768x1435.jpg 768w, https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582-548x1024.jpg 548w, https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582.jpg 1760w\" sizes=\"(max-width: 161px) 100vw, 161px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1760,"height":3289,"file":"2016\/03\/Sort-nederdel-united-color-e1485095237582.jpg","sizes":{"woocommerce_thumbnail":{"file":"Sort-nederdel-united-color-e1485095237582-300x561.jpg","width":300,"height":561,"uncropped":true,"mime_type":"image\/jpeg","source_url":"https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582-300x561.jpg"},"woocommerce_gallery_thumbnail":{"file":"Sort-nederdel-united-color-e1485095237582-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582-100x100.jpg"},"woocommerce_single":{"file":"Sort-nederdel-united-color-e1485095237582-600x1121.jpg","width":600,"height":1121,"mime_type":"image\/jpeg","source_url":"https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582-600x1121.jpg"},"thumbnail":{"file":"Sort-nederdel-united-color-e1485095237582-80x150.jpg","width":80,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582-80x150.jpg"},"medium":{"file":"Sort-nederdel-united-color-e1485095237582-161x300.jpg","width":161,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582-161x300.jpg"},"medium_large":{"file":"Sort-nederdel-united-color-e1485095237582-768x1435.jpg","width":768,"height":1435,"mime_type":"image\/jpeg","source_url":"https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582-768x1435.jpg"},"large":{"file":"Sort-nederdel-united-color-e1485095237582-548x1024.jpg","width":548,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582-548x1024.jpg"},"shop_thumbnail":{"file":"Sort-nederdel-united-color-e1485095237582-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582-100x100.jpg"},"shop_catalog":{"file":"Sort-nederdel-united-color-e1485095237582-300x561.jpg","width":300,"height":561,"uncropped":true,"mime_type":"image\/jpeg","source_url":"https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582-300x561.jpg"},"shop_single":{"file":"Sort-nederdel-united-color-e1485095237582-600x1121.jpg","width":600,"height":1121,"mime_type":"image\/jpeg","source_url":"https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582-600x1121.jpg"},"full":{"file":"Sort-nederdel-united-color-e1485095237582.jpg","width":1760,"height":3289,"mime_type":"image\/jpeg","source_url":"https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":405,"source_url":"https:\/\/caresharevintage.dk\/wp-content\/uploads\/2016\/03\/Sort-nederdel-united-color-e1485095237582.jpg","_links":{"self":[{"href":"https:\/\/caresharevintage.dk\/en\/wp-json\/wp\/v2\/media\/406"}],"collection":[{"href":"https:\/\/caresharevintage.dk\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/caresharevintage.dk\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/caresharevintage.dk\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/caresharevintage.dk\/en\/wp-json\/wp\/v2\/comments?post=406"}]}}